{"id":4293,"date":"2021-10-16T12:05:00","date_gmt":"2021-10-16T10:05:00","guid":{"rendered":"http:\/\/www.areabesos.com\/diario\/?p=4293"},"modified":"2021-10-18T12:08:41","modified_gmt":"2021-10-18T10:08:41","slug":"puigdemont-derrota-a-pedro-sanchez-y-felipe-vi","status":"publish","type":"post","link":"https:\/\/www.areabesos.com\/diario\/puigdemont-derrota-a-pedro-sanchez-y-felipe-vi\/","title":{"rendered":"Puigdemont derrota a Pedro S\u00e1nchez y Felipe VI"},"content":{"rendered":"\n<p><strong>El mismo Pedro S\u00e1nchez dos a\u00f1os despu\u00e9s.<\/strong><\/p>\n\n\n\n<p>Como casi nadie ignora, durante un debate por TV celebrado antes de las elecciones del 10N\/2019 Pedro S\u00e1nchez dijo:<\/p>\n\n\n\n<p>\u201cA ustedes, se\u00f1or Casado, se les fug\u00f3 Puigdemont, y yo me comprometo hoy, aqu\u00ed, a traerlo a Espa\u00f1a y a que rinda cuentas ante la justicia espa\u00f1ola\u201d.<\/p>\n\n\n\n<p>Como muy pocos saben, quiz\u00e1s porque ahora no han querido molestar a un S\u00e1nchez que acaba de firmar con Casado cuatro renovaciones institucionales, Garc\u00eda Ferreras, de La Sexta, le recordaba esto antes de ayer, 14 de octubre:<\/p>\n\n\n\n<p>\u201cTambi\u00e9n dijo usted que traer\u00eda a Carles Puigdemont para ponerlo ante la justicia espa\u00f1ola, y todav\u00eda no ha cumplido\u201d.<\/p>\n\n\n\n<p>A lo que S\u00e1nchez, balbuceando y neg\u00e1ndose a s\u00ed mismo porque sabe que con lo que dijo en 2019 no le hac\u00eda ascos ni a los votantes que, llegado el caso, se ofrecer\u00edan para formar parte del pelot\u00f3n que fusilara al catal\u00e1n, orgullosamente abanderados con la rojigualda, contest\u00f3:<\/p>\n\n\n\n<p>\u201cJe, je, je\u2026, pero bueno, vamos a ver, yo creo que, en fin, quien dice eso, o bien miente, o bien desconoce c\u00f3mo funciona la justicia en Italia, en Europa, en Espa\u00f1a\u201d.<\/p>\n\n\n\n<p>Es decir, \u201cquien dice eso\u201d, sigue siendo el mismo que lo dijo, \u00e9l. Se puede escuchar durante el minuto que transcurre entre el 02:48 y el 03:48 de este programa de Catalunya Radio:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.ccma.cat\/catradio\/alacarta\/la-tarda-de-catalunya-radio\/la-tarda-de-catalunya-radio-de-15-a-16-h-15102021\/audio\/1112789\/\n<\/div><\/figure>\n\n\n\n<p>Se entiende todo, y no se pierda la propuesta de Elisenda Carod para \u201cacabar con el conflicto\u201d. Es una de las mejores de los informativos catalanes en clave de humor durante tiempos represivos. Adem\u00e1s, puede comprobar tambi\u00e9n c\u00f3mo se r\u00eden por igual de los ajenos y de los propios en el minuto anterior al citado.<\/p>\n\n\n\n<p>Tal parece que, en la Espa\u00f1a m\u00e1s espa\u00f1olista, para que un pol\u00edtico poderoso reconozca un error envenenado de maldad, o diga, por ejemplo, \u201cLo siento. Me he equivocado. No volver\u00e1 a ocurrir\u201d, le tienen que pillar disfrutando de sus peores vicios, tras matar un elefante en la jungla africana reservada para delincuentes millonarios y, adem\u00e1s, sentirse tan d\u00e9bil como cualquiera que se haya roto una cadera.<\/p>\n\n\n\n<p><strong>El Borb\u00f3n rey, hijo del Borb\u00f3n rey fugado.<\/strong><\/p>\n\n\n\n<p>El 3 de octubre de 2017 Felipe VI pronunci\u00f3, tambi\u00e9n por TV, su discurso m\u00e1s famoso, pero hoy nadie puede asegurar que, de haber dejado el rey que Rajoy hiciera su trabajo, habr\u00edan ocurrido algunas de las cosas que s\u00ed ocurrieron:<\/p>\n\n\n\n<p>Que Pedro S\u00e1nchez, que sab\u00eda lo del rey en TV, retirara la recusaci\u00f3n que hab\u00eda anunciado un d\u00eda antes contra Soraya por apalizar votantes.<\/p>\n\n\n\n<p>Que Rajoy, siempre partidario de matar las molestias con el tiempo, aprobara un decreto para que grandes empresas pudieran largarse de Catalunya.<\/p>\n\n\n\n<p>Que el citado Rajoy no respondiera a las propuestas para hablar que le enviaba Puigdemont. Ni siquiera lo hizo para embaucar al catal\u00e1n con el cl\u00e1sico truco de las agendas.<\/p>\n\n\n\n<p>Que el 16 de octubre la jueza Lamela decretara prisi\u00f3n sin fianza para los Jordi\u2019s, cuando la acusaci\u00f3n por sedici\u00f3n era del 22 de septiembre.<\/p>\n\n\n\n<p>Que el Parlament proclamara el 27 de octubre la Rep\u00fablica catalana de 18 segundos de vigencia, que un d\u00eda despu\u00e9s el Senado aprobara el 155, que al siguiente Puigdemont trasladara a B\u00e9lgica su residencia y que, porque con algo hay que acabar, meses despu\u00e9s un Rajoy que se hab\u00eda dejado pisar por el rey decidiera regalar el Gobierno a Pedro S\u00e1nchez, pues podr\u00eda haber evitado la peor de las consecuencias de la moci\u00f3n de censura. Para el PP, me refiero.<\/p>\n\n\n\n<p>Y a pesar de todo eso, y del siglo que sumaron las condenas tras el juicio de Marchena, y de los m\u00e1s de 3.000 a\u00fan perseguidos por la \u201cjusticia\u201d, y de los embargos del Tribunal de Cuentas, y de las divisiones internas que siempre sufren quienes no consiguen sus objetivos, el 52% de votos independentistas en las \u00faltimas elecciones catalanas son la verdad principal.<\/p>\n\n\n\n<p>Y tambi\u00e9n que Puigdemont sigue m\u00e1s libre que nunca por Europa, hasta el punto de que ni siquiera podr\u00edan neutralizarlo con el indulto anticipado del que algunos hablan, y que el propio ex president ha rechazado. Al no haber condena previa, podr\u00eda volver a la pol\u00edtica sin limitaciones, a diferencia de Junqueras y el resto de los que han salido de la c\u00e1rcel para moverse bajo una Espada de Damocles.<\/p>\n\n\n\n<p>Tanto fiasco espa\u00f1olista ha sido posible porque, en realidad, Felipe VI apareci\u00f3 en TV aquel 3 de octubre para mantener viva la promesa que, primero, su padre hizo en 1975 al dictador en su lecho de muerte, y poco m\u00e1s de cinco a\u00f1os despu\u00e9s, durante la tarde del 23 de febrero de 1981, a los militares golpistas que tuvieron la fortuna de que no muriera nadie.<\/p>\n\n\n\n<p>La promesa era mantener la unidad de Espa\u00f1a a cualquier precio, un objetivo pol\u00edtico que, al vivirse de manera obsesiva tanto en La Zarzuela como en La Moncloa, termina por facilitar el \u00e9xito de quienes, adem\u00e1s de contar con apoyo electoral, recurren a la inteligencia para tomar decisiones.<\/p>\n\n\n\n<p><span style=\"background-color:#01090c\" class=\"td_text_highlight_marker\">Domingo Sanz<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mismo Pedro S\u00e1nchez dos a\u00f1os despu\u00e9s. Como casi nadie ignora, durante un debate por TV celebrado antes de las elecciones del 10N\/2019 Pedro S\u00e1nchez dijo: \u201cA ustedes, se\u00f1or Casado, se les fug\u00f3 Puigdemont, y yo me comprometo hoy, aqu\u00ed, a traerlo a Espa\u00f1a y a que rinda cuentas ante la justicia espa\u00f1ola\u201d. Como muy [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[],"class_list":{"0":"post-4293","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-opinio"},"_links":{"self":[{"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/posts\/4293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/comments?post=4293"}],"version-history":[{"count":1,"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/posts\/4293\/revisions"}],"predecessor-version":[{"id":4294,"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/posts\/4293\/revisions\/4294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/media\/1632"}],"wp:attachment":[{"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/media?parent=4293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/categories?post=4293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.areabesos.com\/diario\/wp-json\/wp\/v2\/tags?post=4293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}